{"id":9664,"date":"2021-10-19T20:18:50","date_gmt":"2021-10-19T20:18:50","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=9664"},"modified":"2021-10-19T20:18:50","modified_gmt":"2021-10-19T20:18:50","slug":"el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/","title":{"rendered":"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Lo firm\u00f3 horas atr\u00e1s el presidente Alberto Fern\u00e1ndez. En qu\u00e9 consiste el programa y c\u00f3mo se aplicar\u00e1 en las empresas privadas.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente Alberto Fern\u00e1ndez firm\u00f3 el lunes el decreto 711 para convertir los planes sociales en empleo genuino y registrado en el sector privado. El decreto fue publicado este martes en el Bolet\u00edn Oficial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa, seg\u00fan indic\u00f3 el texto en sus considerandos, busca que \u201clos distintos programas de empleo, inclusi\u00f3n laboral y desarrollo socio-productivos destinados a personas desempleadas o con trabajos precarizados se transformen en mecanismos que incentiven la incorporaci\u00f3n de estos trabajadores al empleo asalariado registrado, o a otros modos de desarrollo de actividad productiva ajustados a las formalidades tanto registrales como tributarias\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para cumplir este objetivo se requerir\u00e1n modificaciones en el Programa de Inclusi\u00f3n Socio-Productiva y Desarrollo local \u201cPotenciar Trabajo\u201d y del Programa de Inserci\u00f3n Laboral creado por el Ministerio de Trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Se deber\u00e1n modificar programas de formaci\u00f3n y empleo<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El decreto obliga as\u00ed a los Ministerios de Desarrollo Social y de Trabajo a realizar modificaciones en sus programas de formaci\u00f3n, empleo e intermediaci\u00f3n laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos cambios buscan convertir las diferentes prestaciones de asistencia estatal a personas desempleadas o con trabajos precarizados en \u201cincentivos para la contrataci\u00f3n de sus beneficiarios y beneficiarias bajo la forma de empleo asalariado registrado en el sector privado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prestaci\u00f3n, seg\u00fan el decreto, se considerar\u00e1 \u201cparte integrante del salario respectivo en forma total o parcial, en la forma, plazo y condiciones que se determinen para cada sector de actividad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, producida la discontinuidad del contrato de trabajo, las personas beneficiarias tendr\u00e1n la posibilidad de volver a percibir la asistencia que establece el Programa, si el n\u00famero de cotizaciones al sistema de Seguridad Social no supera los 12 meses dentro de los dos a\u00f1os anteriores al cese del contrato laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Cu\u00e1les son los requisitos que deber\u00e1n cumplir las empresas para sumarse al plan<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente hab\u00eda adelantado esta iniciativa el viernes pasado cuando particip\u00f3 en el coloquio de IDEA. La medida incluso tiene vinculaci\u00f3n con un proyecto impulsado por el titular de la C\u00e1mara de Diputados, Sergio Massa, en el mismo sentido y que el oficialismo considera complementarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plan que adelanta el gobierno recaer\u00e1 en los ministros de Desarrollo Social, Juan Zabaleta, y de Trabajo, Claudio Moroni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la iniciativa, las empresas que se sumen al programa deber\u00e1n cumplir varios requisitos para acceder a los incentivos, entre ellos comprometerse a aumentar la n\u00f3mina del personal y respetar un l\u00edmite en la cantidad de trabajadores alcanzados. Sin embargo, no podr\u00e1n participar las firmas que figuren en el Registro P\u00fablico de Empleadores con Sanciones Laborales (Repsal).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo firm\u00f3 horas atr\u00e1s el presidente Alberto Fern\u00e1ndez. En qu\u00e9 consiste el programa y c\u00f3mo se aplicar\u00e1 en las empresas privadas. El presidente Alberto Fern\u00e1ndez firm\u00f3 el lunes el decreto 711 para convertir los planes sociales en empleo genuino y registrado en el sector privado. El decreto fue publicado este martes en el Bolet\u00edn Oficial. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-9664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"Lo firm\u00f3 horas atr\u00e1s el presidente Alberto Fern\u00e1ndez. En qu\u00e9 consiste el programa y c\u00f3mo se aplicar\u00e1 en las empresas privadas. El presidente Alberto Fern\u00e1ndez firm\u00f3 el lunes el decreto 711 para convertir los planes sociales en empleo genuino y registrado en el sector privado. El decreto fue publicado este martes en el Bolet\u00edn Oficial. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-19T20:18:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/Screenshot_20211019-171559_Facebook.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"587\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal\",\"datePublished\":\"2021-10-19T20:18:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/\"},\"wordCount\":483,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Screenshot_20211019-171559_Facebook.jpg\",\"articleSection\":[\"Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/\",\"name\":\"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Screenshot_20211019-171559_Facebook.jpg\",\"datePublished\":\"2021-10-19T20:18:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Screenshot_20211019-171559_Facebook.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Screenshot_20211019-171559_Facebook.jpg\",\"width\":1080,\"height\":587},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal | CVI NOTICIAS","og_description":"Lo firm\u00f3 horas atr\u00e1s el presidente Alberto Fern\u00e1ndez. En qu\u00e9 consiste el programa y c\u00f3mo se aplicar\u00e1 en las empresas privadas. El presidente Alberto Fern\u00e1ndez firm\u00f3 el lunes el decreto 711 para convertir los planes sociales en empleo genuino y registrado en el sector privado. El decreto fue publicado este martes en el Bolet\u00edn Oficial. [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2021-10-19T20:18:50+00:00","og_image":[{"width":1080,"height":587,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/Screenshot_20211019-171559_Facebook.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal","datePublished":"2021-10-19T20:18:50+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/"},"wordCount":483,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/Screenshot_20211019-171559_Facebook.jpg","articleSection":["Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/","url":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/","name":"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/Screenshot_20211019-171559_Facebook.jpg","datePublished":"2021-10-19T20:18:50+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/Screenshot_20211019-171559_Facebook.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/Screenshot_20211019-171559_Facebook.jpg","width":1080,"height":587},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-publico-el-decreto-para-que-los-beneficiarios-de-planes-sociales-puedan-ser-empleados-en-un-trabajo-formal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"El Gobierno public\u00f3 el decreto para que los beneficiarios de planes sociales puedan ser empleados en un trabajo formal"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/9664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=9664"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/9664\/revisions"}],"predecessor-version":[{"id":9666,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/9664\/revisions\/9666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/9665"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=9664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=9664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=9664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}