{"id":9615,"date":"2021-10-18T19:54:02","date_gmt":"2021-10-18T19:54:02","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=9615"},"modified":"2021-10-18T19:54:02","modified_gmt":"2021-10-18T19:54:02","slug":"elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/","title":{"rendered":"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El Gobierno determin\u00f3 el incremento de $1.000 para las autoridades de mesa que se desempe\u00f1en el pr\u00f3ximo 14 de noviembre en las elecciones generales. Adem\u00e1s, se abonar\u00e1n otros $1000 para aquellos que hayan cumplido esa tarea en las PASO del 12 de septiembre.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este pago extra se confirm\u00f3 a trav\u00e9s del Bolet\u00edn Oficial (BO) y se suma a los $2.500 que hab\u00edan sido estipulados en julio de este a\u00f1o \u201cen concepto de vi\u00e1tico\u201d.\u00a0Tambi\u00e9n se hab\u00eda estimado un monto de $1.500 para aquellas personas que concurran a las capacitaciones previas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En definitiva, quien se desempe\u00f1e como presidente de mesa en las elecciones legislativas del 14 de noviembre recibir\u00e1 un total de $3.500. A este monto, se suma los $1.500 de actividades formaci\u00f3n y capacitaci\u00f3n ya mencionados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La decisi\u00f3n del incremento \u201cen concepto de vi\u00e1ticos\u201d se public\u00f3 en el Bolet\u00edn Oficial, bajo la Resoluci\u00f3n N\u00b0 202, con la autorizaci\u00f3n del ministro del Interior Eduardo \u201cWado\u201d de Pedro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los considerandos de la medida, se especifica que se adopt\u00f3 esta decisi\u00f3n \u201cconsiderando las circunstancias imperantes, y a efectos de coadyuvar a la m\u00e1xima asistencia de las autoridades de mesa para un desarrollo normal, \u00e1gil y transparente de los comicios\u201d, previstos para el pr\u00f3ximo 14 de noviembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, el ministro del Interior autoriz\u00f3 otra suma id\u00e9ntica de $1.000 para \u201clos ciudadanos que se hayan desempe\u00f1ado como autoridades de mesa, habiendo cumplido efectivamente tal funci\u00f3n, tanto en las Elecciones Primarias, Abiertas, Simult\u00e1neas y Obligatorias como en las Elecciones Generales del a\u00f1o 2021\u2033.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La resoluci\u00f3n 202 se suma a la Resoluci\u00f3n N\u00b0 108\/2021 del Ministerio del Interior en la que se implement\u00f3 el pago de una suma fija de $2.500.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno determin\u00f3 el incremento de $1.000 para las autoridades de mesa que se desempe\u00f1en el pr\u00f3ximo 14 de noviembre en las elecciones generales. Adem\u00e1s, se abonar\u00e1n otros $1000 para aquellos que hayan cumplido esa tarea en las PASO del 12 de septiembre. Este pago extra se confirm\u00f3 a trav\u00e9s del Bolet\u00edn Oficial (BO) y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"class_list":["post-9615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"El Gobierno determin\u00f3 el incremento de $1.000 para las autoridades de mesa que se desempe\u00f1en el pr\u00f3ximo 14 de noviembre en las elecciones generales. Adem\u00e1s, se abonar\u00e1n otros $1000 para aquellos que hayan cumplido esa tarea en las PASO del 12 de septiembre. Este pago extra se confirm\u00f3 a trav\u00e9s del Bolet\u00edn Oficial (BO) y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-18T19:54:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/descarga-4-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa\",\"datePublished\":\"2021-10-18T19:54:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/descarga-4-2.jpeg\",\"articleSection\":[\"Politica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/\",\"name\":\"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/descarga-4-2.jpeg\",\"datePublished\":\"2021-10-18T19:54:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/descarga-4-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/descarga-4-2.jpeg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/","og_locale":"es_ES","og_type":"article","og_title":"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa | CVI NOTICIAS","og_description":"El Gobierno determin\u00f3 el incremento de $1.000 para las autoridades de mesa que se desempe\u00f1en el pr\u00f3ximo 14 de noviembre en las elecciones generales. Adem\u00e1s, se abonar\u00e1n otros $1000 para aquellos que hayan cumplido esa tarea en las PASO del 12 de septiembre. Este pago extra se confirm\u00f3 a trav\u00e9s del Bolet\u00edn Oficial (BO) y [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2021-10-18T19:54:02+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/descarga-4-2.jpeg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa","datePublished":"2021-10-18T19:54:02+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/descarga-4-2.jpeg","articleSection":["Politica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/","url":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/","name":"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/descarga-4-2.jpeg","datePublished":"2021-10-18T19:54:02+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/descarga-4-2.jpeg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/10\/descarga-4-2.jpeg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/elecciones-2021-determinan-un-aumento-economico-para-las-autoridades-de-mesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"Elecciones 2021: Determinan un aumento econ\u00f3mico para las autoridades de mesa"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/9615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=9615"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/9615\/revisions"}],"predecessor-version":[{"id":9617,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/9615\/revisions\/9617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/9616"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=9615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=9615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=9615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}