{"id":50091,"date":"2025-10-13T13:15:13","date_gmt":"2025-10-13T16:15:13","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=50091"},"modified":"2025-10-14T09:21:40","modified_gmt":"2025-10-14T12:21:40","slug":"se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/","title":{"rendered":"Se viene la gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Del 17 de octubre al 2 de noviembre, se realizar\u00e1 en la gran campa\u00f1a evangel\u00edstica, un encuentro abierto a toda la comunidad que tendr\u00e1 lugar en la Plaza de los Ni\u00f1os, todos los d\u00edas a partir de las 19 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento, organizado por Casa de Dios Iguaz\u00fa, ofrecer\u00e1 jornadas de m\u00fasica en vivo, mensajes de fe y testimonios, con el prop\u00f3sito de compartir momentos de esperanza, alegr\u00eda y reflexi\u00f3n para toda la familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrevista con: Mario Ibarra (Pastor)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 17 de octubre al 2 de noviembre, se realizar\u00e1 en la gran campa\u00f1a evangel\u00edstica, un encuentro abierto a toda la comunidad que tendr\u00e1 lugar en la Plaza de los Ni\u00f1os, todos los d\u00edas a partir de las 19 horas. El evento, organizado por Casa de Dios Iguaz\u00fa, ofrecer\u00e1 jornadas de m\u00fasica en vivo, mensajes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":50092,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[692,4128],"class_list":["post-50091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-campana","tag-evangelistica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os | CVI NOTICIAS<\/title>\n<meta name=\"description\" content=\"Casa de Dios Iguaz\u00fa invita a la campa\u00f1a evangel\u00edstica con m\u00fasica y mensajes de fe desde el 17 de octubre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"Casa de Dios Iguaz\u00fa invita a la campa\u00f1a evangel\u00edstica con m\u00fasica y mensajes de fe desde el 17 de octubre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-13T16:15:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-14T12:21:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2025\/10\/IMG-20251013-WA0058-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"Se viene la gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os\",\"datePublished\":\"2025-10-13T16:15:13+00:00\",\"dateModified\":\"2025-10-14T12:21:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/\"},\"wordCount\":99,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG-20251013-WA0058-scaled.jpg\",\"keywords\":[\"Campa\u00f1a\",\"Evangelistica\"],\"articleSection\":[\"Sociedad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/\",\"name\":\"Gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG-20251013-WA0058-scaled.jpg\",\"datePublished\":\"2025-10-13T16:15:13+00:00\",\"dateModified\":\"2025-10-14T12:21:40+00:00\",\"description\":\"Casa de Dios Iguaz\u00fa invita a la campa\u00f1a evangel\u00edstica con m\u00fasica y mensajes de fe desde el 17 de octubre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG-20251013-WA0058-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/IMG-20251013-WA0058-scaled.jpg\",\"width\":2560,\"height\":1441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se viene la gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os | CVI NOTICIAS","description":"Casa de Dios Iguaz\u00fa invita a la campa\u00f1a evangel\u00edstica con m\u00fasica y mensajes de fe desde el 17 de octubre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/","og_locale":"es_ES","og_type":"article","og_title":"Gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os | CVI NOTICIAS","og_description":"Casa de Dios Iguaz\u00fa invita a la campa\u00f1a evangel\u00edstica con m\u00fasica y mensajes de fe desde el 17 de octubre","og_url":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2025-10-13T16:15:13+00:00","article_modified_time":"2025-10-14T12:21:40+00:00","og_image":[{"width":2560,"height":1441,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2025\/10\/IMG-20251013-WA0058-scaled.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"Se viene la gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os","datePublished":"2025-10-13T16:15:13+00:00","dateModified":"2025-10-14T12:21:40+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/"},"wordCount":99,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2025\/10\/IMG-20251013-WA0058-scaled.jpg","keywords":["Campa\u00f1a","Evangelistica"],"articleSection":["Sociedad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/","url":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/","name":"Gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2025\/10\/IMG-20251013-WA0058-scaled.jpg","datePublished":"2025-10-13T16:15:13+00:00","dateModified":"2025-10-14T12:21:40+00:00","description":"Casa de Dios Iguaz\u00fa invita a la campa\u00f1a evangel\u00edstica con m\u00fasica y mensajes de fe desde el 17 de octubre","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2025\/10\/IMG-20251013-WA0058-scaled.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2025\/10\/IMG-20251013-WA0058-scaled.jpg","width":2560,"height":1441},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/se-viene-la-gran-campana-evangelistica-en-la-plaza-de-los-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"Se viene la gran campa\u00f1a evangel\u00edstica en la Plaza de los Ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/50091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=50091"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/50091\/revisions"}],"predecessor-version":[{"id":50093,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/50091\/revisions\/50093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/50092"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=50091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=50091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=50091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}