{"id":26256,"date":"2023-07-14T04:02:46","date_gmt":"2023-07-14T04:02:46","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=26256"},"modified":"2023-07-14T04:02:46","modified_gmt":"2023-07-14T04:02:46","slug":"inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/","title":{"rendered":"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Mientras Silvina Luna lucha por su vida en el Hospital Italiano, la Justicia lo inhabilit\u00f3 de manera provisoria hasta que se confirme o no su condena a 4 a\u00f1os de prisi\u00f3n por mala praxis.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El m\u00e9dico cirujano An\u00edbal Lotocki fue inhabilitado para ejercer la medicina de manera provisoria hasta que se confirme o no la condena de 4 a\u00f1os de prisi\u00f3n que le fue dictada por los delitos de lesiones graves contra Silvina Luna y otras tres famosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La decisi\u00f3n fue tomada por la Sala 3 de la C\u00e1mara Nacional de Casaci\u00f3n a pedido del fiscal Sandro Abraldes y del abogado Fernando Burlando, quien hab\u00eda solicitado que se le suspenda de forma provisional la licencia m\u00e9dica a Lotocki, mientras Silvina Luna contin\u00faa internada en grave estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dictamen fiscal fue enviado a la C\u00e1mara Nacional de Casaci\u00f3n en lo Criminal y Correccional donde se solicit\u00f3 que Lotocki no ejerza la medicina y el comercio en el \u00e1mbito de la est\u00e9tica y la cosm\u00e9tica mientras se revisa su condena a cuatro a\u00f1os de prisi\u00f3n y cinco de inhabilitaci\u00f3n por las lesiones sufridas a cuatro pacientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el expediente N\u00ba 50949\/2015, el fiscal hace lugar al pedido de la querellante Pamela Estefan\u00eda Sosa y ex pareja del cirujano, y destaca que es preocupante que el m\u00e9dico siga atendiendo a pacientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEsta Fiscal\u00eda General entiende que la medida cautelar en cuesti\u00f3n resulta procedente y merece ser decretada en forma inmediata por los Sres. Jueces de la C\u00e1mara, en atenci\u00f3n al peligro latente que se cierne sobre la salud de aquellos que hasta el d\u00eda de hoy contin\u00faan someti\u00e9ndose a las intervenciones del m\u00e9dico Lotocki\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, resalta que \u00abla presunci\u00f3n de acierto de que goza toda sentencia judicial autoriza el dictado de la medida cautelar peticionada\u00bb con el objeto de \u00abneutralizar el riesgo potencial que se deriva del ejercicio de la medicina, y de la cirug\u00eda est\u00e9tica, puesto que pesa sobre Lotocki una condena fundada precisamente en el quebranto de numerosos deberes inherentes a su actuaci\u00f3n profesional\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva resoluci\u00f3n, que inhabilita al m\u00e9dico para ejercer la medicina, fue firmada por los jueces H\u00e9ctor Mario Magari\u00f1os y Pablo Jantus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lotocki fue condenado en febrero de 2022 por el juez Carlos Rengel Mirat a cuatro a\u00f1os de prisi\u00f3n y le fij\u00f3 una inhabilitaci\u00f3n para ejercer la medicina por cinco a\u00f1os, al encontrarlo culpable de las lesiones graves que sufrieron cuatro pacientes tras hacerse distintos procedimientos quir\u00fargicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El delito en su contra es por \u00ablesiones graves reiteradas en cuatro oportunidades\u00bb sobre sus pacientes Gabriela Trenchi, Silvina Luna, Stefan\u00eda Xipolitakis y Pamela Sosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Silvina Luna permanece internada en la sala de terapia intensiva del Hospital Italiano desde hace un mes por una hipercalcemia que le produjo una insuficiencia renal, la que habr\u00eda sido originada por las cirug\u00edas est\u00e9ticas que Lotocki le realiz\u00f3 en 2011.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras Silvina Luna lucha por su vida en el Hospital Italiano, la Justicia lo inhabilit\u00f3 de manera provisoria hasta que se confirme o no su condena a 4 a\u00f1os de prisi\u00f3n por mala praxis. El m\u00e9dico cirujano An\u00edbal Lotocki fue inhabilitado para ejercer la medicina de manera provisoria hasta que se confirme o no la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-26256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"Mientras Silvina Luna lucha por su vida en el Hospital Italiano, la Justicia lo inhabilit\u00f3 de manera provisoria hasta que se confirme o no su condena a 4 a\u00f1os de prisi\u00f3n por mala praxis. El m\u00e9dico cirujano An\u00edbal Lotocki fue inhabilitado para ejercer la medicina de manera provisoria hasta que se confirme o no la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-14T04:02:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/07\/64cf2118d08a870c0817466787a38ebf_M.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina\",\"datePublished\":\"2023-07-14T04:02:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/\"},\"wordCount\":517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/64cf2118d08a870c0817466787a38ebf_M.jpg\",\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/\",\"name\":\"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/64cf2118d08a870c0817466787a38ebf_M.jpg\",\"datePublished\":\"2023-07-14T04:02:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/64cf2118d08a870c0817466787a38ebf_M.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/64cf2118d08a870c0817466787a38ebf_M.jpg\",\"width\":768,\"height\":507},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/","og_locale":"es_ES","og_type":"article","og_title":"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina | CVI NOTICIAS","og_description":"Mientras Silvina Luna lucha por su vida en el Hospital Italiano, la Justicia lo inhabilit\u00f3 de manera provisoria hasta que se confirme o no su condena a 4 a\u00f1os de prisi\u00f3n por mala praxis. El m\u00e9dico cirujano An\u00edbal Lotocki fue inhabilitado para ejercer la medicina de manera provisoria hasta que se confirme o no la [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2023-07-14T04:02:46+00:00","og_image":[{"width":768,"height":507,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/07\/64cf2118d08a870c0817466787a38ebf_M.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina","datePublished":"2023-07-14T04:02:46+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/"},"wordCount":517,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/07\/64cf2118d08a870c0817466787a38ebf_M.jpg","articleSection":["Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/","url":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/","name":"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/07\/64cf2118d08a870c0817466787a38ebf_M.jpg","datePublished":"2023-07-14T04:02:46+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/07\/64cf2118d08a870c0817466787a38ebf_M.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/07\/64cf2118d08a870c0817466787a38ebf_M.jpg","width":768,"height":507},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/inhabilitaron-a-anibal-lotocki-para-ejercer-la-medicina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"Inhabilitaron a An\u00edbal Lotocki para ejercer la medicina"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/26256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=26256"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/26256\/revisions"}],"predecessor-version":[{"id":26258,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/26256\/revisions\/26258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/26257"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=26256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=26256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=26256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}