{"id":25502,"date":"2023-06-15T11:35:09","date_gmt":"2023-06-15T11:35:09","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=25502"},"modified":"2023-06-15T11:35:09","modified_gmt":"2023-06-15T11:35:09","slug":"dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/","title":{"rendered":"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>En Argentina se diagnostican anualmente cerca de 5 mil casos de esta enfermedad, lo que lo ubica como el quinto tumor m\u00e1s frecuente en nuestro pa\u00eds, detr\u00e1s de los c\u00e1nceres de mama, colon, pr\u00f3stata y pulm\u00f3n.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El D\u00eda Mundial del c\u00e1ncer renal se conmemora el tercer jueves de junio y, en el marco del mismo, desde la Asociaci\u00f3n de Pacientes VICARE de C\u00e1ncer Renal y de Vejiga destacaron la importancia de la detecci\u00f3n temprana, la que generalmente se logra en forma incidental, en estudios de rutina cuando se consulta al m\u00e9dico en forma peri\u00f3dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan cifras publicadas por el Instituto Nacional del C\u00e1ncer de la Agencia Internacional de Investigaci\u00f3n sobre el C\u00e1ncer (IARC), en Argentina se diagnostican anualmente cerca de 5 mil casos de c\u00e1ncer de ri\u00f1\u00f3n, lo que lo ubica como el quinto tumor m\u00e1s frecuente en nuestro pa\u00eds, detr\u00e1s de los c\u00e1nceres de mama, colon, pr\u00f3stata y pulm\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, seg\u00fan el informe de la Direcci\u00f3n de Estad\u00edsticas e Informaci\u00f3n en Salud (DEIS) del Ministerio de Salud de la Naci\u00f3n correspondiente al a\u00f1o 2021, fallecen por a\u00f1o en Argentina por esta causa cerca de 2 mil personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien el c\u00e1ncer renal suele no presentar s\u00edntomas en sus estadios iniciales, los especialistas recomiendan estar atentos a signos como la presencia de sangre en la orina, dolor persistente en la zona lumbar, fiebre sin causa aparente, p\u00e9rdida de peso, fatiga, anemia, la autopalpaci\u00f3n de alg\u00fan bulto y tambi\u00e9n la aparici\u00f3n de hipertensi\u00f3n en personas que no eran hipertensas. Por supuesto, ante cualquiera de estos s\u00edntomas, se recomienda consultar con el m\u00e9dico de cabecera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claudia Miranda, presidenta de VICARE, insiste en la importancia de los controles anuales con el m\u00e9dico de cabecera, mucho m\u00e1s a\u00fan si se tiene alg\u00fan familiar que haya presentado c\u00e1ncer renal. \u201cDesde hace 3 a\u00f1os, momento en el que naci\u00f3 nuestra asociaci\u00f3n, venimos pregonando para propiciar controles de rutina y evitar aquellas condiciones que pueden predisponer el desarrollo de esta enfermedad\u201d, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Factores de riesgo y tratamiento<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los factores de riesgo para desarrollar c\u00e1ncer de ri\u00f1\u00f3n, se destacan el tabaquismo, la obesidad y la hipertensi\u00f3n arterial, mientras que tambi\u00e9n hay otros factores no modificables, como pertenecer al sexo masculino, tener m\u00e1s de 60 a\u00f1os, antecedentes familiares de esta enfermedad, ser afrodescendiente o estar en sesiones de di\u00e1lisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al tratamiento, este depender\u00e1 de varias circunstancias, como el estadio del tumor, su localizaci\u00f3n y el estado de salud del paciente. La cirug\u00eda suele ser la primera opci\u00f3n y representa el tratamiento curativo m\u00e1s importante. No obstante, tambi\u00e9n hay medicamentos de \u00faltima generaci\u00f3n para los estadios m\u00e1s avanzados de la enfermedad, entre los que se encuentran terapias dirigidas (generalmente de administraci\u00f3n oral), inmunoterapia (intravenosa) o la combinaci\u00f3n de ambas. La llegada y disponibilidad de estas alternativas terap\u00e9uticas se increment\u00f3 en los \u00faltimos a\u00f1os y contribuye a brindar a los pacientes una importante sobrevida y una buena calidad de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVICARE integra una red de m\u00e1s de 102 ONG de c\u00e1ncer del pa\u00eds con el objetivo de contener y asistir a todas aquellas personas que viven con una enfermedad oncol\u00f3gica. Queremos aprovechar este D\u00eda Mundial para invitar a los pacientes a que se acerquen a nuestra instituci\u00f3n e insistir con el control de los factores de riesgo y con la visita peri\u00f3dica con el m\u00e9dico de cabecera para detectar tempranamente esta y cualquier otra enfermedad oncol\u00f3gica\u201d, concluy\u00f3 Claudia Miranda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta asociaci\u00f3n fue fundada con el objetivo de reducir la mortalidad de la enfermedad y acompa\u00f1ar al paciente y sus familiares, para lo cual se trabaja en educar, difundir, prevenir, ayudar, concientizar e investigar todo lo referente al c\u00e1ncer renal desde Argentina hacia el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los objetivos se la misma son: brindarle contenci\u00f3n a paciente y familiares; generar programas de concientizaci\u00f3n sobre la prevenci\u00f3n del c\u00e1ncer renal a la comunidad en general; se enfoca en el \u201cTratamiento Saludable\u201d unificando la buena nutrici\u00f3n, actividad f\u00edsica, tratamiento m\u00e9dico y acompa\u00f1amiento psicol\u00f3gico del paciente y familiares y trabaja en la creaci\u00f3n de la Comunidad VICARE, base de datos de pacientes, su seguimiento y el apoyo log\u00edstico completo para cualquier necesidad que soliciten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Argentina se diagnostican anualmente cerca de 5 mil casos de esta enfermedad, lo que lo ubica como el quinto tumor m\u00e1s frecuente en nuestro pa\u00eds, detr\u00e1s de los c\u00e1nceres de mama, colon, pr\u00f3stata y pulm\u00f3n. El D\u00eda Mundial del c\u00e1ncer renal se conmemora el tercer jueves de junio y, en el marco del mismo, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-25502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"En Argentina se diagnostican anualmente cerca de 5 mil casos de esta enfermedad, lo que lo ubica como el quinto tumor m\u00e1s frecuente en nuestro pa\u00eds, detr\u00e1s de los c\u00e1nceres de mama, colon, pr\u00f3stata y pulm\u00f3n. El D\u00eda Mundial del c\u00e1ncer renal se conmemora el tercer jueves de junio y, en el marco del mismo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-15T11:35:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/06\/Cancer-de-rinon-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana\",\"datePublished\":\"2023-06-15T11:35:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/\"},\"wordCount\":779,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Cancer-de-rinon-scaled-1.jpg\",\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/\",\"name\":\"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Cancer-de-rinon-scaled-1.jpg\",\"datePublished\":\"2023-06-15T11:35:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Cancer-de-rinon-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Cancer-de-rinon-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana | CVI NOTICIAS","og_description":"En Argentina se diagnostican anualmente cerca de 5 mil casos de esta enfermedad, lo que lo ubica como el quinto tumor m\u00e1s frecuente en nuestro pa\u00eds, detr\u00e1s de los c\u00e1nceres de mama, colon, pr\u00f3stata y pulm\u00f3n. El D\u00eda Mundial del c\u00e1ncer renal se conmemora el tercer jueves de junio y, en el marco del mismo, [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2023-06-15T11:35:09+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/06\/Cancer-de-rinon-scaled-1.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana","datePublished":"2023-06-15T11:35:09+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/"},"wordCount":779,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/06\/Cancer-de-rinon-scaled-1.jpg","articleSection":["Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/","url":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/","name":"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/06\/Cancer-de-rinon-scaled-1.jpg","datePublished":"2023-06-15T11:35:09+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/06\/Cancer-de-rinon-scaled-1.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/06\/Cancer-de-rinon-scaled-1.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/dia-mundial-del-cancer-renal-destacan-la-importancia-de-la-deteccion-temprana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Mundial del c\u00e1ncer renal: destacan la importancia de la detecci\u00f3n temprana"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/25502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=25502"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/25502\/revisions"}],"predecessor-version":[{"id":25504,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/25502\/revisions\/25504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/25503"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=25502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=25502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=25502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}