{"id":17067,"date":"2022-06-29T11:13:30","date_gmt":"2022-06-29T11:13:30","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=17067"},"modified":"2022-06-29T11:13:30","modified_gmt":"2022-06-29T11:13:30","slug":"el-gobierno-lanzo-el-previaje-2022","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/","title":{"rendered":"El Gobierno lanz\u00f3 el Previaje 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Se trata del programa que devuelve el 50% de lo gastado en un viaje en forma de cr\u00e9dito. Conoc\u00e9 las novedades de una nueva edici\u00f3n<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de la resoluci\u00f3n 303\/2022 publicada este mi\u00e9rcoles en el Bolet\u00edn Oficial, el Ministerio de Turismo y Deportes de la Naci\u00f3n lanz\u00f3 el programa \u00abPreViaje Edici\u00f3n 2022\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de una de las pol\u00edticas m\u00e1s exitosas del gobierno en la pospandemia, que consiste en la devoluci\u00f3n a los turistas del 50% de lo gastado en rubros, actividades y prestadores integrantes de la cadena tur\u00edstica, en concepto de cr\u00e9dito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La anterior edici\u00f3n alcanz\u00f3 a m\u00e1s de 4,5 millones de turistas y moviliz\u00f3 m\u00e1s de 150 mil millones de pesos en la cadena tur\u00edstica. En este marco, la disposici\u00f3n argumenta que \u00abse estima pertinente dar continuidad a la pol\u00edtica de incentivo a la preventa de servicios tur\u00edsticos nacionales mediante el lanzamiento de una tercera edici\u00f3n del Programa, con miras a promover el turismo nacional y el consumo de servicios tur\u00edsticos en temporada baja, contribuyendo a distribuir la demanda tur\u00edstica y mitigar los efectos de la estacionalidad de la actividad tur\u00edstica\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al programa podr\u00e1n acceder al mismo todas las personas mayores de 18 a\u00f1os residentes en Argentina que cumplan con los requerimientos establecidos y cuya solicitud sea aprobada por la Subsecretar\u00eda de Promoci\u00f3n Tur\u00edstica y Nuevos Productos del ministerio de Turismo y Deportes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para acceder se deber\u00e1 contar con Clave \u00danica de Identificaci\u00f3n Tributaria (CUIT) y\/o C\u00f3digo \u00danico de Identificaci\u00f3n Laboral (CUIL), y su identificaci\u00f3n se realizar\u00e1 a trav\u00e9s de la aplicaci\u00f3n MI ARGENTINA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn esta oportunidad, el Previaje no solo incentivar\u00e1 la demanda, sino que tambi\u00e9n est\u00e1 pensado para seguir fortaleciendo este sector, que es estrat\u00e9gico y muy importante para el pa\u00eds. Tendr\u00e1 una aplicaci\u00f3n m\u00e1s quir\u00fargica, con una parte de desarrollo en infraestructura tur\u00edstica con una inversi\u00f3n p\u00fablica y privada\u201d, detall\u00f3 el titular del \u00e1rea en el Gobierno Nacional, Mat\u00edas Lammens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para solicitar el beneficio, la persona debe acceder a la web del programa, ingresar y acreditar los comprobantes de compras anticipadas y\/o boletos a\u00e9reos o terrestres dentro de la plataforma, de acuerdo al viaje o concepto que corresponda y bajo la modalidad establecida. No tendr\u00e1 l\u00edmite respecto a la cantidad de compras anticipadas que desee acreditar ni respecto de la cantidad de viajes que puede generar dentro de la plataforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez realizado, los beneficiarios percibir\u00e1n el cup\u00f3n de cr\u00e9dito, el cual podr\u00e1n utilizar \u00fanicamente para la adquisici\u00f3n de servicios tur\u00edsticos brindados dentro del territorio nacional y ofrecidos por parte de empresas o establecimientos correspondientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, las compras anticipadas en concepto de servicios de alojamiento (como campings y\/o refugios de monta\u00f1a, hoteles, hoster\u00edas, caba\u00f1as, etc), agencias de viajes (servicios de empresas de viajes y turismo y servicios de agencias de turismo), transporte (aerocomercial regular de cabotaje de pasajeros y terrestre de larga distancia) podr\u00e1n generar cr\u00e9dito en concepto de beneficio por un monto de hasta $100.000.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que las compras anticipadas en concepto de servicios de excursiones (como traslado de trenes especiales y servicios de excursiones lacustres, fluviales y mar\u00edtimas con fines tur\u00edsticos, servicios de transporte automotor de pasajeros para el turismo, servicios de alquiler de equipos de transporte terrestre sin operaci\u00f3n ni tripulaci\u00f3n), servicios de centros ( de esqu\u00ed, de pesca deportiva, de turismo salud, turismo termal y\/o similares, turismo aventura, ecoturismo) y bodegas, jardines bot\u00e1nicos, zool\u00f3gicos, parques de diversiones, parques tem\u00e1ticos, parques recreativos, museos y preservaci\u00f3n de lugares y edificios hist\u00f3ricos podr\u00e1n generar cr\u00e9dito en concepto de beneficio por un monto total de hasta $5.000.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque en uno de sus art\u00edculos, el anexo de la resoluci\u00f3n aclara que el monto m\u00e1ximo del cr\u00e9dito que un\/a beneficiario\/a podr\u00e1 percibir en el marco del programa es de $100.000. Una vez alcanzada dicha suma, ya no podr\u00e1 volver a generar cr\u00e9dito ni beneficio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los cupones de cr\u00e9dito estar\u00e1n disponibles para su utilizaci\u00f3n a partir de la fecha de prestaci\u00f3n de el\/los servicio\/s adquirido\/s y hasta el 31 de diciembre de 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, no generar\u00e1n beneficio ni estar\u00e1n alcanzadas por el Programa aquellas compras anticipadas ni sus respectivos comprobantes, por un importe total menor a $1.000. Asimismo, el monto m\u00ednimo que deber\u00e1 acreditarse en concepto de una o m\u00e1s compras anticipadas para acceder al beneficio es de $10.000.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata del programa que devuelve el 50% de lo gastado en un viaje en forma de cr\u00e9dito. Conoc\u00e9 las novedades de una nueva edici\u00f3n A trav\u00e9s de la resoluci\u00f3n 303\/2022 publicada este mi\u00e9rcoles en el Bolet\u00edn Oficial, el Ministerio de Turismo y Deportes de la Naci\u00f3n lanz\u00f3 el programa \u00abPreViaje Edici\u00f3n 2022\u00bb. Se trata [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-17067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Gobierno lanz\u00f3 el Previaje 2022 | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno lanz\u00f3 el Previaje 2022 | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"Se trata del programa que devuelve el 50% de lo gastado en un viaje en forma de cr\u00e9dito. Conoc\u00e9 las novedades de una nueva edici\u00f3n A trav\u00e9s de la resoluci\u00f3n 303\/2022 publicada este mi\u00e9rcoles en el Bolet\u00edn Oficial, el Ministerio de Turismo y Deportes de la Naci\u00f3n lanz\u00f3 el programa \u00abPreViaje Edici\u00f3n 2022\u00bb. Se trata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-29T11:13:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/06\/IMG-20220628-WA0071.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1066\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"El Gobierno lanz\u00f3 el Previaje 2022\",\"datePublished\":\"2022-06-29T11:13:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/\"},\"wordCount\":787,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG-20220628-WA0071.jpg\",\"articleSection\":[\"Turismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/\",\"name\":\"El Gobierno lanz\u00f3 el Previaje 2022 | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG-20220628-WA0071.jpg\",\"datePublished\":\"2022-06-29T11:13:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG-20220628-WA0071.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG-20220628-WA0071.jpg\",\"width\":1066,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/el-gobierno-lanzo-el-previaje-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno lanz\u00f3 el Previaje 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno lanz\u00f3 el Previaje 2022 | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno lanz\u00f3 el Previaje 2022 | CVI NOTICIAS","og_description":"Se trata del programa que devuelve el 50% de lo gastado en un viaje en forma de cr\u00e9dito. Conoc\u00e9 las novedades de una nueva edici\u00f3n A trav\u00e9s de la resoluci\u00f3n 303\/2022 publicada este mi\u00e9rcoles en el Bolet\u00edn Oficial, el Ministerio de Turismo y Deportes de la Naci\u00f3n lanz\u00f3 el programa \u00abPreViaje Edici\u00f3n 2022\u00bb. Se trata [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2022-06-29T11:13:30+00:00","og_image":[{"width":1066,"height":1600,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/06\/IMG-20220628-WA0071.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"El Gobierno lanz\u00f3 el Previaje 2022","datePublished":"2022-06-29T11:13:30+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/"},"wordCount":787,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/06\/IMG-20220628-WA0071.jpg","articleSection":["Turismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/","url":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/","name":"El Gobierno lanz\u00f3 el Previaje 2022 | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/06\/IMG-20220628-WA0071.jpg","datePublished":"2022-06-29T11:13:30+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/06\/IMG-20220628-WA0071.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/06\/IMG-20220628-WA0071.jpg","width":1066,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/el-gobierno-lanzo-el-previaje-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"El Gobierno lanz\u00f3 el Previaje 2022"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/17067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=17067"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/17067\/revisions"}],"predecessor-version":[{"id":17069,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/17067\/revisions\/17069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/17068"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=17067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=17067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=17067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}