{"id":13059,"date":"2022-02-09T15:39:01","date_gmt":"2022-02-09T15:39:01","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=13059"},"modified":"2022-02-09T15:39:01","modified_gmt":"2022-02-09T15:39:01","slug":"la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/","title":{"rendered":"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>La Divisi\u00f3n Antidrogas Eldorado de la Polic\u00eda Federal secuestr\u00f3 m\u00e1s de 35kg de Marihuana y detuvo a dos personas que se dedicaban a enviar estupefacientes al barrio de Liniers para su comercializaci\u00f3n.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante la realizaci\u00f3n de amplias tareas investigativas por parte del personal de la Divisi\u00f3n Antidrogas Eldorado de la Polic\u00eda Federal Argentina, lograron desbaratar una banda que traficaba marihuana desde la Provincia de Misiones hacia el Barrio de Liniers de la Capital Federal. Estas pesquisas dieron como resultado la detenci\u00f3n de 2 hombres, siendo estos los responsables de la organizaci\u00f3n. Tambi\u00e9n se realizaron 2 allanamientos entre la provincia de Misiones, y en Capital Federal, logr\u00e1ndose el secuestro de cerca de 35Kgs de marihuana, tel\u00e9fonos, dinero en efectivo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122422_Word.jpg\"><img decoding=\"async\" width=\"936\" height=\"470\" data-src=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122422_Word.jpg\" alt=\"\" class=\"wp-image-13061 lazyload\" data-srcset=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122422_Word.jpg 936w, https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122422_Word-300x151.jpg 300w, https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122422_Word-768x386.jpg 768w\" data-sizes=\"(max-width: 936px) 100vw, 936px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 936px; --smush-placeholder-aspect-ratio: 936\/470;\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Todo comenz\u00f3 a ra\u00edz de que personal de la Unidad Antidrogas se encontraba realizando control de encomiendas en un local de la Ciudad de Wanda Provincia de Misiones, en donde el can antinarc\u00f3ticos \u201cSherlock\u201d, perteneciente a esa Divisi\u00f3n, logra detectar un bulto la cual ten\u00edan como destino la ciudad Aut\u00f3noma de Buenos Aires.<br><br>En esa oportunidad el Juzgado Federal de Eldorado ordena la apertura y requisa de las mismas, logrando determinar que, en el interior de la encomienda, se encontraban ocultos m\u00e1s de 30 bultos con sustancia estupefaciente que se hallaban ocultos en dos cestos de basura recubiertos con espuma poliuret\u00e1nica, modalidad est\u00e1 que utilizan buscando sortear los controles con el can detector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese contexto se comenz\u00f3 con la pesquisa que derivo en trabajos investigativos realizados en la ciudad aut\u00f3noma de Buenos Aires por la Divisi\u00f3n Operaciones Federales de la Polic\u00eda Federal Argentina a modo de cooperaci\u00f3n, mientras que los trabajos de campo llevados a cabo en la ciudad de Puerto Libertad, Provincia de Misiones fueron realizados por los investigadores de la Divisi\u00f3n Antidrogas Eldorado. Donde luego de ubicar a los part\u00edcipes de esta maniobra delictiva se solicit\u00f3 las correspondientes \u00f3rdenes de allanamiento y detenci\u00f3n al Juzgado Federal interviniente, logr\u00e1ndose as\u00ed la detenci\u00f3n en el barrio de Liniers CABA, de un hombre mayor de edad, mientras que en la ciudad de Libertad se logr\u00f3 la detenci\u00f3n otro de los masculinos encargados de mandar el estupefaciente a la Capital Federal.<br><br>Todo el trabajo realizado fue llevado a cabo ante la intervenci\u00f3n el Juzgado Federal de Eldorado a cargo del Dr. Alejandro Marcos GALLANDAD LUZURIAGA, por ante la Secretaria de la Dra. Cinthya SANDERG<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Divisi\u00f3n Antidrogas Eldorado de la Polic\u00eda Federal secuestr\u00f3 m\u00e1s de 35kg de Marihuana y detuvo a dos personas que se dedicaban a enviar estupefacientes al barrio de Liniers para su comercializaci\u00f3n. Mediante la realizaci\u00f3n de amplias tareas investigativas por parte del personal de la Divisi\u00f3n Antidrogas Eldorado de la Polic\u00eda Federal Argentina, lograron desbaratar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-13059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"La Divisi\u00f3n Antidrogas Eldorado de la Polic\u00eda Federal secuestr\u00f3 m\u00e1s de 35kg de Marihuana y detuvo a dos personas que se dedicaban a enviar estupefacientes al barrio de Liniers para su comercializaci\u00f3n. Mediante la realizaci\u00f3n de amplias tareas investigativas por parte del personal de la Divisi\u00f3n Antidrogas Eldorado de la Polic\u00eda Federal Argentina, lograron desbaratar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-09T15:39:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122510_Word.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"891\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires\",\"datePublished\":\"2022-02-09T15:39:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/\"},\"wordCount\":436,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Screenshot_20220209-122510_Word.jpg\",\"articleSection\":[\"Policiales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/\",\"name\":\"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Screenshot_20220209-122510_Word.jpg\",\"datePublished\":\"2022-02-09T15:39:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Screenshot_20220209-122510_Word.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Screenshot_20220209-122510_Word.jpg\",\"width\":891,\"height\":423},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/","og_locale":"es_ES","og_type":"article","og_title":"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires | CVI NOTICIAS","og_description":"La Divisi\u00f3n Antidrogas Eldorado de la Polic\u00eda Federal secuestr\u00f3 m\u00e1s de 35kg de Marihuana y detuvo a dos personas que se dedicaban a enviar estupefacientes al barrio de Liniers para su comercializaci\u00f3n. Mediante la realizaci\u00f3n de amplias tareas investigativas por parte del personal de la Divisi\u00f3n Antidrogas Eldorado de la Polic\u00eda Federal Argentina, lograron desbaratar [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2022-02-09T15:39:01+00:00","og_image":[{"width":891,"height":423,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122510_Word.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires","datePublished":"2022-02-09T15:39:01+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/"},"wordCount":436,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122510_Word.jpg","articleSection":["Policiales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/","url":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/","name":"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122510_Word.jpg","datePublished":"2022-02-09T15:39:01+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122510_Word.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/02\/Screenshot_20220209-122510_Word.jpg","width":891,"height":423},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/la-policia-federal-desarticulo-una-banda-narco-que-operaba-desde-misiones-a-la-ciudad-de-buenos-aires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"La Polic\u00eda Federal desarticul\u00f3 una banda narco que operaba desde Misiones a la ciudad de Buenos Aires"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/13059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=13059"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/13059\/revisions"}],"predecessor-version":[{"id":13062,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/13059\/revisions\/13062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/13060"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=13059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=13059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=13059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}