{"id":12451,"date":"2022-01-18T13:15:51","date_gmt":"2022-01-18T13:15:51","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=12451"},"modified":"2022-01-18T13:15:51","modified_gmt":"2022-01-18T13:15:51","slug":"en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/","title":{"rendered":"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina"},"content":{"rendered":"\n<p><strong><em>La portabilidad en telefon\u00eda fija, que contempla la posibilidad de que el usuario pueda cambiar de operador manteniendo su n\u00famero de tel\u00e9fono, comenzar\u00e1 a aplicarse el 18 de febrero pr\u00f3ximo en las ciudades de La Plata, Mar del Plata y Salta, seg\u00fan lo acordado entre los principales actores del mercado con la empresa administradora de base de datos y el Ente Nacional de Comunicaciones (Enacom).<\/em><\/strong><\/p>\n\n\n\n<p>Hasta ahora los consumidores en la Argentina pueden cambiar de operador de telefon\u00eda m\u00f3vil sin cambiar su n\u00famero, un sistema que, aun con sus complicaciones, otorg\u00f3 a los usuarios el derecho de retener su n\u00famero sin importar qu\u00e9 equipo u operador tengan.<\/p>\n\n\n\n<p>La portabilidad de las l\u00edneas telef\u00f3nicas fijas, que implica de hecho cambiar la viejas conexiones denominadas \u00abpar de cobre\u00bb a otras m\u00e1s modernas como fibra \u00f3ptica, pueden llevar en el corto plazo, por ejemplo, a la desaparici\u00f3n del uso del prefijo 15 para poder comunicarse con una l\u00ednea m\u00f3vil.<\/p>\n\n\n\n<p>Tambi\u00e9n desaparecer\u00e1 la limitaci\u00f3n geogr\u00e1fica, porque este ordenamiento de operadores a futuro podr\u00eda permitir la portabilidad geogr\u00e1fica de la numeraci\u00f3n, lo que puede significar que el n\u00famero de un abonado de C\u00f3rdoba -con el prefijo 0351- sea portado y ofrecido por un operador en Mar del Plata.<\/p>\n\n\n\n<p>\u00abSe podr\u00eda avanzar en un esquema de tarifa \u00fanica nacional, quitar el 15 de los n\u00fameros celulares, unificar y ordenar el plan de numeraci\u00f3n del pa\u00eds, incluso implementar portabilidad fija-m\u00f3vil \/ m\u00f3vil-fija como existe por ejemplo en Chile y USA\u00bb, sostuvieron los impulsores de la medida en un documento interno del comit\u00e9 de Cabase, unn asociaci\u00f3n civil sin fines de lucro que nuclea a los principales operadores y proveedores de internet de la Argentina.<\/p>\n\n\n\n<p>Tras el puntapi\u00e9 inicial previsto para febrero, para la portabilidad fija la previsi\u00f3n es extender la implementaci\u00f3n a otras 20 zonas (por prefijo) a partir del 3 de marzo pr\u00f3ximo y terminar de cubrir todo el pa\u00eds a mediados de ese mes.<\/p>\n\n\n\n<p>La portabilidad en fijos es un reclamo hist\u00f3rico de los operadores entrantes, desde que concret\u00f3 la apertura del mercado en diciembre del 2000.<\/p>\n\n\n\n<p>Hoy por hoy, el servicio de telefon\u00eda fija que supo subsidiar la extensi\u00f3n de las redes m\u00f3viles viene perdiendo usuarios, al punto de ubicarse en una penetraci\u00f3n de 16,64 l\u00edneas cada 100 habitantes y del 53,84% en hogares, seg\u00fan los \u00faltimos datos publicados por el Enacom, que datan del segundo trimestre del a\u00f1o pasado.<\/p>\n\n\n\n<p>Asimismo, los ingresos generados por el servicio de telefon\u00eda fija, considerando tanto a las dos grandes prestadoras (Telecom y Movistar) como a las cooperativas, sumaron alrededor de $17.606 millones en segundo trimestre del a\u00f1o pasado.<\/p>\n\n\n\n<p>A fines de 2021, el Ente Nacional de Comunicaciones otorg\u00f3 a las empresas del sector que no tienen hoy prestaci\u00f3n de servicio de telefon\u00eda fija el routing number (RN), que funciona como identificador para cada operador ya sea una pyme con servicios de internet o un operador m\u00f3vil virtual .<\/p>\n\n\n\n<p>Con esta herramienta y el sistema de portabilidad iniciado, los operadores podr\u00e1n portar la numeraci\u00f3n de tipo fija que hoy est\u00e1 en pares de cobre a nuevas tecnolog\u00edas VoIP, redes de fibra \u00f3ptica, sistemas de PBX (centralita) en la nube, algo que ha sido muy requerido por las empresas en el \u00faltimo tiempo por la pandemia, el desarrollo del teletrabajo y el home office.<\/p>\n\n\n\n<p>Desde Cabase explicaron que \u00abla portabilidad para la numeraci\u00f3n fija le da competencia a un servicio que antes no ten\u00eda, sumando valor y desarrollo a las redes fijas de internet y nuevas tecnolog\u00edas\u00bb.<\/p>\n\n\n\n<p>Seg\u00fan datos del comit\u00e9 t\u00e9cnico de portabilidad t\u00e9cnica (Copon), la portabilidad num\u00e9rica m\u00f3vil, en operaci\u00f3n desde marzo del a\u00f1o 2012, fue utilizada hasta ahora por m\u00e1s de 15 millones de l\u00edneas m\u00f3viles.<\/p>\n\n\n\n<p>Para hacer efectiva la portabilidad, tanto en m\u00f3viles como en fija, se licit\u00f3 la actuaci\u00f3n de un tercero distinto a las empresas del sector que oficia como administrado de base de datos.<\/p>\n\n\n\n<p>En Argentina la empresa Administradora de la Base de Datos (ABD) es APA S.A.; un joint venture conformado por iConectiv y Telmark, con contrato hasta 2026.<\/p>\n\n\n\n<p>El sector se divide entre quienes anhelan la implementaci\u00f3n de la portabilidad en fijos para sumar un servicio a sus clientes de internet.<\/p>\n\n\n\n<p>La visi\u00f3n contrapuesta sostiene que es un negocio que ya no es rentable en la actualidad y la puesta en marcha de la portabilidad terminar\u00e1 siendo un alivio para las grandes empresas.<\/p>\n\n\n\n<p>En rigor, la portabilidad acompa\u00f1ar\u00e1 la migraci\u00f3n de las redes de par de cobre a servicios que corren por fibra \u00f3ptica. La misma migraci\u00f3n que vienen haciendo las grandes operadoras.<\/p>\n\n\n\n<p>Para las grandes empresas entrantes el desaf\u00edo es \u00abmodernizar un sistema que ha quedado desactualizado\u00bb.<\/p>\n\n\n\n<p>\u00abVenimos del mundo del switching y hay que pasar a sistemas modernos con interconexiones mediante las redes de datos que dar\u00e1n m\u00e1s flexibilidad y redundancia\u00bb, w los especialistas.<\/p>\n\n\n\n<p>Los n\u00fameros de tel\u00e9fono son considerados como el identificador multioperador mundial m\u00e1s antiguo que existe, sobre el cual se desarrollan otros servicios.<\/p>\n\n\n\n<p>Tener un sistema de numeraci\u00f3n sano, moderno y ordenado entre los distintos operadores permite ofrecer estos servicios y seguir desarrollando m\u00e1s prestaciones garantizando el derecho de todos los argentinos a conservar su identidad, el n\u00famero de tel\u00e9fono de su celular, casa, comercio, negocio o empresa, coinciden los especialistas.<\/p>\n\n\n\n<p><strong>Fuente: T\u00e9lam<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La portabilidad en telefon\u00eda fija, que contempla la posibilidad de que el usuario pueda cambiar de operador manteniendo su n\u00famero de tel\u00e9fono, comenzar\u00e1 a aplicarse el 18 de febrero pr\u00f3ximo en las ciudades de La Plata, Mar del Plata y Salta, seg\u00fan lo acordado entre los principales actores del mercado con la empresa administradora de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-12451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"La portabilidad en telefon\u00eda fija, que contempla la posibilidad de que el usuario pueda cambiar de operador manteniendo su n\u00famero de tel\u00e9fono, comenzar\u00e1 a aplicarse el 18 de febrero pr\u00f3ximo en las ciudades de La Plata, Mar del Plata y Salta, seg\u00fan lo acordado entre los principales actores del mercado con la empresa administradora de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T13:15:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/01\/f608x342-145903_175626_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"608\" \/>\n\t<meta property=\"og:image:height\" content=\"342\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina\",\"datePublished\":\"2022-01-18T13:15:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/\"},\"wordCount\":951,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/f608x342-145903_175626_0.jpg\",\"articleSection\":[\"Informaci\u00f3n General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/\",\"name\":\"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/f608x342-145903_175626_0.jpg\",\"datePublished\":\"2022-01-18T13:15:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/f608x342-145903_175626_0.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/f608x342-145903_175626_0.jpg\",\"width\":608,\"height\":342},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina | CVI NOTICIAS","og_description":"La portabilidad en telefon\u00eda fija, que contempla la posibilidad de que el usuario pueda cambiar de operador manteniendo su n\u00famero de tel\u00e9fono, comenzar\u00e1 a aplicarse el 18 de febrero pr\u00f3ximo en las ciudades de La Plata, Mar del Plata y Salta, seg\u00fan lo acordado entre los principales actores del mercado con la empresa administradora de [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2022-01-18T13:15:51+00:00","og_image":[{"width":608,"height":342,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/01\/f608x342-145903_175626_0.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina","datePublished":"2022-01-18T13:15:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/"},"wordCount":951,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/01\/f608x342-145903_175626_0.jpg","articleSection":["Informaci\u00f3n General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/","url":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/","name":"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/01\/f608x342-145903_175626_0.jpg","datePublished":"2022-01-18T13:15:51+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/01\/f608x342-145903_175626_0.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2022\/01\/f608x342-145903_175626_0.jpg","width":608,"height":342},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/en-febrero-comienza-sistema-de-portabilidad-numerica-para-usuarios-de-telefonia-fija-en-la-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"En febrero comienza sistema de portabilidad num\u00e9rica para usuarios de telefon\u00eda fija en la Argentina"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/12451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=12451"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/12451\/revisions"}],"predecessor-version":[{"id":12453,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/12451\/revisions\/12453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/12452"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=12451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=12451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=12451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}