{"id":10928,"date":"2021-11-25T20:06:48","date_gmt":"2021-11-25T20:06:48","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=10928"},"modified":"2021-11-25T20:06:48","modified_gmt":"2021-11-25T20:06:48","slug":"conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/","title":{"rendered":"Conmebol anunci\u00f3 que elimina el \u00abgol de visitante\u00bb para el 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>El organismo se\u00f1al\u00f3 que \u00aben adelante todos los goles de los torneos tendr\u00e1n el mismo valor, ya no se considerar\u00e1 como un factor de desempate los tantos convertidos en calidad de visitante\u00bb.<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Conmebol anunci\u00f3 este jueves a trav\u00e9s de sus redes sociales que eliminar\u00e1 el llamado \u201cgol de visitante\u201d de todos sus torneos, por lo cual la medida se aplicar\u00e1 en la Copa Libertadores y en la Copa Sudamericana a partir del a\u00f1o pr\u00f3ximo, a la vez que consider\u00f3 que la misma apunta a una \u201cmayor justicia deportiva\u201d.<br><br>\u00abLa Conmebol elimina el &#8216;gol de visitante&#8217;. En adelante todos los goles de los torneos de la Conmebol tendr\u00e1n el mismo valor, ya no se considerar\u00e1 como un factor de desempate los tantos convertidos en calidad de visitante\u00bb, se\u00f1al\u00f3 la entidad.<br><br>Asimismo, el organismo que preside Alejandro Dom\u00ednguez a\u00f1adi\u00f3 en un mensaje que difundi\u00f3 en sus redes sociales: \u00abCon ello, se apunta a una mayor justicia deportiva\u00bb. La decisi\u00f3n de la Conmebol se implementar\u00e1 a partir de las competiciones que se lleven a cabo en 2022.<br><br>Ante esta situaci\u00f3n, desde ahora en los partidos que disputen las competencias con partidos de ida y vuelta&nbsp; -Libertadores, Sudamericana y Recopa- y que termine igualado en goles, continuar\u00e1 con la definici\u00f3n por penales, tal como sucedi\u00f3 hasta la edici\u00f3n 2004.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El organismo se\u00f1al\u00f3 que \u00aben adelante todos los goles de los torneos tendr\u00e1n el mismo valor, ya no se considerar\u00e1 como un factor de desempate los tantos convertidos en calidad de visitante\u00bb. La Conmebol anunci\u00f3 este jueves a trav\u00e9s de sus redes sociales que eliminar\u00e1 el llamado \u201cgol de visitante\u201d de todos sus torneos, por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10929,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-10928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conmebol anunci\u00f3 que elimina el &quot;gol de visitante&quot; para el 2022 | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conmebol anunci\u00f3 que elimina el &quot;gol de visitante&quot; para el 2022 | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"El organismo se\u00f1al\u00f3 que \u00aben adelante todos los goles de los torneos tendr\u00e1n el mismo valor, ya no se considerar\u00e1 como un factor de desempate los tantos convertidos en calidad de visitante\u00bb. La Conmebol anunci\u00f3 este jueves a trav\u00e9s de sus redes sociales que eliminar\u00e1 el llamado \u201cgol de visitante\u201d de todos sus torneos, por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-25T20:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/Steaua_vs._CFR_Cluj_in_2010.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"Conmebol anunci\u00f3 que elimina el \u00abgol de visitante\u00bb para el 2022\",\"datePublished\":\"2021-11-25T20:06:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Steaua_vs._CFR_Cluj_in_2010.jpg\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/\",\"name\":\"Conmebol anunci\u00f3 que elimina el \\\"gol de visitante\\\" para el 2022 | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Steaua_vs._CFR_Cluj_in_2010.jpg\",\"datePublished\":\"2021-11-25T20:06:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Steaua_vs._CFR_Cluj_in_2010.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Steaua_vs._CFR_Cluj_in_2010.jpg\",\"width\":640,\"height\":427,\"caption\":\"SONY DSC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conmebol anunci\u00f3 que elimina el \u00abgol de visitante\u00bb para el 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conmebol anunci\u00f3 que elimina el \"gol de visitante\" para el 2022 | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Conmebol anunci\u00f3 que elimina el \"gol de visitante\" para el 2022 | CVI NOTICIAS","og_description":"El organismo se\u00f1al\u00f3 que \u00aben adelante todos los goles de los torneos tendr\u00e1n el mismo valor, ya no se considerar\u00e1 como un factor de desempate los tantos convertidos en calidad de visitante\u00bb. La Conmebol anunci\u00f3 este jueves a trav\u00e9s de sus redes sociales que eliminar\u00e1 el llamado \u201cgol de visitante\u201d de todos sus torneos, por [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2021-11-25T20:06:48+00:00","og_image":[{"width":640,"height":427,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/Steaua_vs._CFR_Cluj_in_2010.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"Conmebol anunci\u00f3 que elimina el \u00abgol de visitante\u00bb para el 2022","datePublished":"2021-11-25T20:06:48+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/Steaua_vs._CFR_Cluj_in_2010.jpg","articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/","url":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/","name":"Conmebol anunci\u00f3 que elimina el \"gol de visitante\" para el 2022 | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/Steaua_vs._CFR_Cluj_in_2010.jpg","datePublished":"2021-11-25T20:06:48+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/Steaua_vs._CFR_Cluj_in_2010.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/Steaua_vs._CFR_Cluj_in_2010.jpg","width":640,"height":427,"caption":"SONY DSC"},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/conmebol-anuncio-que-elimina-el-gol-de-visitante-para-el-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"Conmebol anunci\u00f3 que elimina el \u00abgol de visitante\u00bb para el 2022"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/10928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=10928"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/10928\/revisions"}],"predecessor-version":[{"id":10930,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/10928\/revisions\/10930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/10929"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=10928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=10928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=10928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}