{"id":10243,"date":"2021-11-02T18:22:32","date_gmt":"2021-11-02T18:22:32","guid":{"rendered":"https:\/\/cvinoticias.com\/v3\/?p=10243"},"modified":"2021-11-02T18:22:32","modified_gmt":"2021-11-02T18:22:32","slug":"arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras","status":"publish","type":"post","link":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/","title":{"rendered":"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>Influencers de la pintura misionera reflejar\u00e1n sus conocimientos en masterclass. Alberto Mathot, Ernesto Engel y Bernardo Neumann compartir\u00e1n escenario en una tarde donde el arte y los negocios tendr\u00e1n su espacio.<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La invitaci\u00f3n es para el viernes 5 de noviembre, desde las 16 horas en el Centro Cultural Vicente Cidade de Posadas, con cupos limitados e inscripci\u00f3n previa al 3764 \u2013 112101, bajo estricto protocolo sanitario por el Coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los grandes representantes del pincel en la Tierra Colorada brindar\u00e1n una jornada donde plasmar\u00e1n todos sus conocimientos en el marco de una masterclass abierta al p\u00fablico interesado en la tem\u00e1tica y en incorporar todos los aportes que brindar\u00e1n estos expertos del lienzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la presentaci\u00f3n se tocar\u00e1n temas relacionados a c\u00f3mo acceder al mercado econ\u00f3mico de la mano del arte, el pasaje de las obras al mundo de la criptomoneda, la tecnolog\u00eda y el arte como industria, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento es organizado por la Fundaci\u00f3n Agencia para el Desarrollo Econ\u00f3mico de Misiones (ADEMI), junto con el Gobierno de Misiones, a trav\u00e9s del Ministerio de Coordinaci\u00f3n de Gabinete y Cultura de la provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un poco m\u00e1s sobre los artistas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alberto Mathot naci\u00f3 en Leandro N. Alem. Es Profesor de Ense\u00f1anza Primaria y desde chico demostr\u00f3 placer por el dibujo y la pintura, don que logr\u00f3 manifestarse plasmando su amor por la naturaleza. Trabaja con un estilo cargado de realismo y variedades tonales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bernardo Neumann es de Puerto Rico. Egres\u00f3 como profesor de dibujo y pintura del Instituto Superior Antonio Ruiz de Montoya donde se especializ\u00f3 en t\u00e9cnicas de pintura. Sus trabajos han sido definidos como de estilo abstracto y surrealista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ernesto Engel naci\u00f3 en Posadas. Es Profesor de Dibujo y Pintura y se ha desempe\u00f1ado como docente en la Universidad Nacional de Misiones (UNaM). Para crear sus cuadros emplea t\u00e9cnicas antiguas de pintura; una es el temple, creada por los egipcios. La segunda proviene del Renacimiento italiano, originada en Venecia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Influencers de la pintura misionera reflejar\u00e1n sus conocimientos en masterclass. Alberto Mathot, Ernesto Engel y Bernardo Neumann compartir\u00e1n escenario en una tarde donde el arte y los negocios tendr\u00e1n su espacio. La invitaci\u00f3n es para el viernes 5 de noviembre, desde las 16 horas en el Centro Cultural Vicente Cidade de Posadas, con cupos limitados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-10243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras | CVI NOTICIAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras | CVI NOTICIAS\" \/>\n<meta property=\"og:description\" content=\"Influencers de la pintura misionera reflejar\u00e1n sus conocimientos en masterclass. Alberto Mathot, Ernesto Engel y Bernardo Neumann compartir\u00e1n escenario en una tarde donde el arte y los negocios tendr\u00e1n su espacio. La invitaci\u00f3n es para el viernes 5 de noviembre, desde las 16 horas en el Centro Cultural Vicente Cidade de Posadas, con cupos limitados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/\" \/>\n<meta property=\"og:site_name\" content=\"CVI NOTICIAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cvinoticias\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-02T18:22:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/IMG-20211102-WA0104.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"f1000024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"f1000024\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/\"},\"author\":{\"name\":\"f1000024\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\"},\"headline\":\"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras\",\"datePublished\":\"2021-11-02T18:22:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG-20211102-WA0104.jpg\",\"articleSection\":[\"Informaci\u00f3n General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/\",\"name\":\"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras | CVI NOTICIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG-20211102-WA0104.jpg\",\"datePublished\":\"2021-11-02T18:22:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG-20211102-WA0104.jpg\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG-20211102-WA0104.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"name\":\"CVI NOTICIAS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\"},\"alternateName\":\"CVI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#organization\",\"name\":\"CVI NOTICIAS\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"contentUrl\":\"https:\\\/\\\/cvinoticias.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-cropped-cropped-3-1.png\",\"width\":95,\"height\":122,\"caption\":\"CVI NOTICIAS\"},\"image\":{\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cvinoticias\",\"https:\\\/\\\/www.instagram.com\\\/cvinoticias\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CVINOTICIAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/#\\\/schema\\\/person\\\/2db77e3c6bc03c538495d7b2b8be9b66\",\"name\":\"f1000024\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g\",\"caption\":\"f1000024\"},\"url\":\"https:\\\/\\\/cvinoticias.com\\\/v3\\\/author\\\/f1000024\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras | CVI NOTICIAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/","og_locale":"es_ES","og_type":"article","og_title":"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras | CVI NOTICIAS","og_description":"Influencers de la pintura misionera reflejar\u00e1n sus conocimientos en masterclass. Alberto Mathot, Ernesto Engel y Bernardo Neumann compartir\u00e1n escenario en una tarde donde el arte y los negocios tendr\u00e1n su espacio. La invitaci\u00f3n es para el viernes 5 de noviembre, desde las 16 horas en el Centro Cultural Vicente Cidade de Posadas, con cupos limitados [&hellip;]","og_url":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/","og_site_name":"CVI NOTICIAS","article_publisher":"https:\/\/www.facebook.com\/cvinoticias","article_published_time":"2021-11-02T18:22:32+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/IMG-20211102-WA0104.jpg","type":"image\/jpeg"}],"author":"f1000024","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"f1000024","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/#article","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/"},"author":{"name":"f1000024","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66"},"headline":"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras","datePublished":"2021-11-02T18:22:32+00:00","mainEntityOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/IMG-20211102-WA0104.jpg","articleSection":["Informaci\u00f3n General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/","url":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/","name":"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras | CVI NOTICIAS","isPartOf":{"@id":"https:\/\/cvinoticias.com\/v3\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/#primaryimage"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/#primaryimage"},"thumbnailUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/IMG-20211102-WA0104.jpg","datePublished":"2021-11-02T18:22:32+00:00","breadcrumb":{"@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/#primaryimage","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/IMG-20211102-WA0104.jpg","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2021\/11\/IMG-20211102-WA0104.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/cvinoticias.com\/v3\/arte-y-negocios-como-moverse-en-el-mercado-para-vender-las-obras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cvinoticias.com\/v3\/"},{"@type":"ListItem","position":2,"name":"Arte y negocios, c\u00f3mo moverse en el mercado para vender las obras"}]},{"@type":"WebSite","@id":"https:\/\/cvinoticias.com\/v3\/#website","url":"https:\/\/cvinoticias.com\/v3\/","name":"CVI NOTICIAS","description":"","publisher":{"@id":"https:\/\/cvinoticias.com\/v3\/#organization"},"alternateName":"CVI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cvinoticias.com\/v3\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cvinoticias.com\/v3\/#organization","name":"CVI NOTICIAS","url":"https:\/\/cvinoticias.com\/v3\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/","url":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","contentUrl":"https:\/\/cvinoticias.com\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-cropped-cropped-3-1.png","width":95,"height":122,"caption":"CVI NOTICIAS"},"image":{"@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cvinoticias","https:\/\/www.instagram.com\/cvinoticias\/","https:\/\/www.youtube.com\/@CVINOTICIAS"]},{"@type":"Person","@id":"https:\/\/cvinoticias.com\/v3\/#\/schema\/person\/2db77e3c6bc03c538495d7b2b8be9b66","name":"f1000024","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4fe7459cfc51ff5129ce1a732bbef5928568b8092d412ef95611616376bbeed?s=96&d=mm&r=g","caption":"f1000024"},"url":"https:\/\/cvinoticias.com\/v3\/author\/f1000024\/"}]}},"_links":{"self":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/10243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/comments?post=10243"}],"version-history":[{"count":1,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/10243\/revisions"}],"predecessor-version":[{"id":10245,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/posts\/10243\/revisions\/10245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media\/10244"}],"wp:attachment":[{"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/media?parent=10243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/categories?post=10243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cvinoticias.com\/v3\/wp-json\/wp\/v2\/tags?post=10243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}